{"id":55977,"date":"2021-05-26T09:10:35","date_gmt":"2021-05-26T09:10:35","guid":{"rendered":"https:\/\/safariclub.gr\/product\/minoan_route\/"},"modified":"2025-03-31T12:33:47","modified_gmt":"2025-03-31T09:33:47","slug":"minoan_route","status":"publish","type":"product","link":"https:\/\/safariclub.gr\/fr\/produit\/minoan_route\/","title":{"rendered":"Minoan Route"},"content":{"rendered":"<p>D\u00e9couvrez la partie centrale de la Cr\u00e8te avec sa mythologie, faune, flore, et de nombreuses informations cocasses et int\u00e9ressantes \u00e0 propos de la Cr\u00e8te et de sa vie locale.<\/p>\n<p>Votre excursion commence d\u00e8s que vous rencontrez vos chauffeurs qui vous conduirons au premier arr\u00eat, au barrage d\u2019Aposelemi. Notre excursion se poursuit dans les sentiers et oliveraies pour rejoindre les ruines de l\u2019aqueduc romain de Lyttos. La prochaine halte est le village tranquille de Kastamonitsa o\u00f9 nous joindrons les locaux pour une d\u00e9gustation de raki et d\u2019huile d\u2019olive. Ensuite d\u00e9butera r\u00e9ellement la partie hors-piste de la journ\u00e9e, gravissant la montagne en suivant le sentier minoen qui nous conduira chez un berger, o\u00f9 vous aurez la chance de nourrir les ch\u00e8vres et ensuite de d\u00e9guster du fromage fait maison.<\/p>\n<p>De l\u00e0, nous poursuivons notre chemin jusqu\u2019au magnifique point de vue, d\u2019o\u00f9 vous pouvez voir le sentier ancien des minoens ainsi que le plateau du Lassithi. <b><\/b><\/p>\n<p>Nous descendons sur le plateau pour l&rsquo;explorer, puis nous le traversons et nous nous arr\u00eatons pour un d\u00e9licieux d\u00e9jeuner traditionnel accompagn\u00e9 de vin \u00e0 volont\u00e9 (option v\u00e9g\u00e9tarienne disponible) !<\/p>\n<p>En poursuivant notre route, nous arriverons au village de Krassi, notre derni\u00e8re halte de la journ\u00e9e, un village connu pour son platane \u00e2g\u00e9 de 2000 ans et ses fontaines naturelles d\u2019eau de source.<\/p>\n<p>C\u2019est une journ\u00e9e pleine de surprises et vous n\u2019oublierez certainement pas cette sortie avec<\/p>\n<p>Great adventure!!<\/p>\n<p>Points forts:<\/p>\n<ul>\n<li>barrage Aposelimi= le village englouti de Sfendili<\/li>\n<li>Lyttos= aqueduc Romain<\/li>\n<li>Kastamonitsa= d\u00e9gustation de raki et d\u2019huile d\u2019olive<\/li>\n<li>Berger= nourrir les ch\u00e8vres et d\u00e9gustation de fromage<\/li>\n<li>Sentier minoen= Point de vue<\/li>\n<li>Plateau de Lassithi = fermes et moulins a vent<\/li>\n<li>D\u00e9jeuner = cuisine traditionnelle cr\u00e9toise avec vin local et eau<\/li>\n<li>Krassi= platane \u00e2g\u00e9 de 2000 ans<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez la partie centrale de la Cr\u00e8te avec sa mythologie, faune, flore, et de nombreuses informations cocasses et int\u00e9ressantes \u00e0 propos de la Cr\u00e8te et de sa vie locale. Votre excursion commence d\u00e8s que vous rencontrez vos chauffeurs qui vous conduirons au premier arr\u00eat, au barrage d\u2019Aposelemi. Notre excursion se poursuit dans les sentiers et&hellip;<\/p>\n","protected":false},"featured_media":57861,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[1428],"product_tag":[1516,1517,1518,1520,1521,1522,1523,1524,1526,1527,1528,1529,1530],"class_list":["post-55977","product","type-product","status-publish","has-post-thumbnail","product_cat-land-rover-safari-fr","product_tag-land-rover-jeep-safari-form-ammoudara-fr","product_tag-land-rover-jeep-safari-from-analipsi-fr","product_tag-land-rover-jeep-safari-from-anissaras-fr","product_tag-land-rover-jeep-safari-from-gouves-fr","product_tag-land-rover-jeep-safari-from-heraklion-fr","product_tag-land-rover-jeep-safari-from-hersonissos-fr","product_tag-land-rover-jeep-safari-from-kokkini-hani-fr","product_tag-land-rover-jeep-safari-from-koutouloufari-fr","product_tag-land-rover-jeep-safari-from-malia-fr","product_tag-land-rover-jeep-safari-from-milatos-fr","product_tag-land-rover-jeep-safari-from-piskopiano-fr","product_tag-land-rover-jeep-safari-from-sissi-fr","product_tag-land-rover-jeep-safari-from-stalis-fr","description-off","first","instock","sold-individually","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/product\/55977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/comments?post=55977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/media\/57861"}],"wp:attachment":[{"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/media?parent=55977"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/product_brand?post=55977"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/product_cat?post=55977"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/product_tag?post=55977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}