{"id":52647,"date":"2018-03-13T12:16:46","date_gmt":"2018-03-13T12:16:46","guid":{"rendered":"https:\/\/safariclub.gr\/?page_id=52647"},"modified":"2019-04-09T12:30:14","modified_gmt":"2019-04-09T12:30:14","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/safariclub.gr\/fr\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>\t\t\t\t[vc_row][vc_column][vc_column_text]Derni\u00e8re mise \u00e0 jour: 27\/04\/2017<\/p>\n<p>Au Safari Club, nous reconnaissons que gagner et conserver votre confiance est l&rsquo;une des choses les plus importantes que nous faisons en tant qu&rsquo;entreprise. Prot\u00e9ger votre vie priv\u00e9e est une responsabilit\u00e9 que nous prenons tr\u00e8s au s\u00e9rieux.<\/p>\n<p>Nous avons pr\u00e9par\u00e9 cette politique de confidentialit\u00e9 pour vous aider \u00e0 comprendre comment Safari Club recueille, utilise et cherche \u00e0 prot\u00e9ger les renseignements personnels (d\u00e9finis ci-dessous) que vous nous fournissez sur nos sites Web, applications mobiles, par courriel et par nos fournisseurs de services et partenaires de distribution. . Cette politique de confidentialit\u00e9 n&rsquo;aborde pas, et nous ne sommes pas responsables, la confidentialit\u00e9, les informations ou autres pratiques d&rsquo;un tiers, y compris les partenaires de distribution tiers, les fournisseurs et les voyagistes, et tout tiers exploitant un site contenir un lien. En t\u00e9l\u00e9chargeant, acc\u00e9dant ou utilisant nos sites ou contenus, ou en utilisant une application Safari Club (\u00ab\u00a0Application\u00a0\u00bb) sur un t\u00e9l\u00e9phone mobile, tablette ou appareil similaire (\u00ab\u00a0Appareil\u00a0\u00bb), ou en nous fournissant des informations relatives \u00e0 nos sites Web, applications mobiles ou d&rsquo;autres sites ou services, vous acceptez les termes et conditions de cette politique de confidentialit\u00e9.<\/p>\n<p>Qui nous sommes<br \/>\nSafari Club est un service en ligne qui permet aux utilisateurs de rechercher, trouver et r\u00e9server leur Land Rover Safari en Cr\u00e8te en Gr\u00e8ce. Les produits et services de Safari Club sont disponibles sur safariclub.gr et sur les sites Web affili\u00e9s \u00e0 Safari Club en Gr\u00e8ce ainsi que sur les applications Safari Club.<\/p>\n<p>Safariclub.gr est notre site web phare, o\u00f9 nous offrons notre gamme compl\u00e8te de produits et de services directement aux consommateurs.<br \/>\nAu Safari Club, nous travaillons \u00e9galement avec des soci\u00e9t\u00e9s affili\u00e9es qui distribuent nos produits et services aux consommateurs via leurs sites Web individuels.<br \/>\nNous travaillons \u00e9galement avec les distributeurs (voir ci-dessous) qui g\u00e8rent l&rsquo;h\u00e9bergement, l&rsquo;achat et le paiement de nos produits et services.<br \/>\nSi vous fournissez des informations directement \u00e0 nos affili\u00e9s, distributeurs ou fournisseurs, les termes de leurs politiques de confidentialit\u00e9 respectives, et non cette politique de confidentialit\u00e9, s&rsquo;appliqueront \u00e0 ces divulgations. Vous devez examiner attentivement les politiques de confidentialit\u00e9 du partenaire affili\u00e9, du distributeur ou du fournisseur avant de fournir des informations \u00e0 ces tiers. Voir \u00abNos affili\u00e9s, distributeurs et fournisseurs\u00bb ci-dessous pour plus d&rsquo;informations.<\/p>\n<p>Quelles informations collectons-nous?<br \/>\nEn g\u00e9n\u00e9ral<br \/>\nNous recevons et stockons toutes les informations que vous saisissez sur nos sites Web ou nous les fournissons de toute autre mani\u00e8re. Nous recueillons deux types d&rsquo;informations aupr\u00e8s de vous sur nos sites Web, applications mobiles, par e-mail, et par le biais de nos fournisseurs de services et partenaires de distribution. Les informations personnelles sont des informations qui vous identifient personnellement, telles que votre nom et pr\u00e9nom, votre adresse e-mail, votre num\u00e9ro de t\u00e9l\u00e9phone, vos adresses postale et \u00e9lectronique, votre nom d&rsquo;utilisateur et votre mot de passe, ainsi que vos informations de facturation. Nous collectons \u00e9galement d&rsquo;autres informations qui ne vous identifient pas personnellement, telles que le sexe, le pays de r\u00e9sidence et d&rsquo;autres informations d\u00e9mographiques.<\/p>\n<p>Lorsque vous vous inscrivez \u00e0 Safari Club, nous demandons des informations de base, y compris votre nom et votre adresse e-mail, et d&rsquo;autres informations telles que votre lieu de s\u00e9jour. Vous pouvez choisir de ne pas nous fournir d&rsquo;informations, mais en g\u00e9n\u00e9ral certaines informations vous concernant sont n\u00e9cessaires pour que vous puissiez recevoir des offres pertinentes de Safari Club et de ses partenaires et b\u00e9n\u00e9ficier d&rsquo;autres avantages en tant que membre inscrit. Par exemple, pour acheter des produits ou services, il est n\u00e9cessaire que vous divulguiez des informations personnelles, y compris votre nom, adresse, adresse e-mail, num\u00e9ro de t\u00e9l\u00e9phone et autres informations d&rsquo;identification personnelle. Si vous ne fournissez pas de renseignements personnels lors de l&rsquo;achat d&rsquo;un produit ou d&rsquo;un service de notre fournisseur, nous ne pouvons pas confirmer votre achat ou faciliter votre r\u00e9servation.<\/p>\n<p>Dans certains cas, nous pouvons \u00e9galement demander d&rsquo;autres informations telles que les donn\u00e9es d\u00e9mographiques, notamment votre pays de r\u00e9sidence, votre sexe, votre \u00e2ge, vos habitudes de voyage, etc. Nous utilisons \u00e9galement des cookies pour collecter des informations sur les performances et l&rsquo;ergonomie de nos sites. .<\/p>\n<p>Informations provenant d&rsquo;autres sources.<br \/>\nNous pouvons \u00e9galement obtenir p\u00e9riodiquement des informations personnelles et non personnelles vous concernant aupr\u00e8s d&rsquo;entit\u00e9s affili\u00e9es, de partenaires commerciaux et d&rsquo;autres sources tierces ind\u00e9pendantes et les ajouter \u00e0 d&rsquo;autres informations vous concernant. Par exemple, si vous visitez Safari Club en cliquant sur un site exploit\u00e9 par l&rsquo;un de nos partenaires commerciaux et que vous vous \u00eates enregistr\u00e9 aupr\u00e8s de ce partenaire, les informations que vous avez fournies \u00e0 ce partenaire peuvent \u00eatre partag\u00e9es avec nous. comme coordonn\u00e9es et informations d\u00e9mographiques. Autre exemple, si vous acc\u00e9dez \u00e0 des services tiers, tels que les services de m\u00e9dias sociaux, via notre site Web ou avant d&rsquo;acc\u00e9der \u00e0 notre site Web, nous pouvons collecter des informations telles que votre nom d&rsquo;utilisateur et d&rsquo;autres informations. Nous travaillerons avec nos partenaires existants et futurs partenaires potentiels pour am\u00e9liorer et personnaliser votre utilisation de notre site Web conform\u00e9ment aux pratiques d\u00e9crites dans cette politique de confidentialit\u00e9.<\/p>\n<p>Informations automatiques<br \/>\nLorsque vous visitez safariclub.gr ou l&rsquo;un des oSi vous h\u00e9bergez nos pages Web, notre serveur Web reconna\u00eet automatiquement et recueille votre adresse IP, qui est assign\u00e9e par votre fournisseur d&rsquo;acc\u00e8s Internet et ne vous identifie pas personnellement, logiciel de navigateur Web et site Web r\u00e9f\u00e9rant. Pour nous aider \u00e0 analyser l&rsquo;utilisation de nos sites Web et des services connexes, et pour vous envoyer des communications plus pertinentes, nous collectons \u00e9galement d&rsquo;autres informations sur votre activit\u00e9 en ligne, telles que le contenu consult\u00e9, les pages visit\u00e9es et les recherches et \/ ou r\u00e9servations. facilit\u00e9 ou fait. L&rsquo;un de nos objectifs dans la collecte de ces informations automatiques est de nous aider \u00e0 comprendre les int\u00e9r\u00eats et les pr\u00e9f\u00e9rences de nos utilisateurs et \u00e0 personnaliser votre exp\u00e9rience utilisateur. Par exemple, si vous visitez fr\u00e9quemment H\u00e9raklion et Chania, nous pouvons vous envoyer des avis sp\u00e9ciaux \u00e9num\u00e9rant les offres et les produits populaires pour ces destinations. Si vous \u00eates abonn\u00e9 \u00e0 l&rsquo;une de nos communications marketing par e-mail, y compris les bulletins d&rsquo;information et les alertes de destination, vous devez fournir des informations personnelles telles que votre nom et votre adresse e-mail et d&rsquo;autres informations telles que votre pays d&rsquo;origine. excursion avec des fournisseurs tiers facilit\u00e9s par Safari Club, nous collecterons les informations de paiement de votre part, y compris votre adresse de facturation. Informations sur l&#8217;emplacement et autres informations sur les appareils Lorsque vous utilisez une application sur un appareil, nous collecterons et utiliserons des informations similaires fa\u00e7ons et \u00e0 des fins similaires que lorsque vous utilisez le site Web Safari Club. En outre, nous pouvons collecter des informations sur votre emplacement si vous avez demand\u00e9 \u00e0 votre appareil d&rsquo;envoyer ces informations \u00e0 l&rsquo;Application via les param\u00e8tres de confidentialit\u00e9 de ce dernier ou si vous avez import\u00e9 des photos marqu\u00e9es avec des informations de localisation. Nous pouvons utiliser les informations de localisation collect\u00e9es \u00e0 partir de votre Appareil ou de vos photos pour am\u00e9liorer votre utilisation de l&rsquo;Application en vous fournissant du contenu pertinent et de la publicit\u00e9 contextuelle. Par exemple, nous pouvons utiliser votre position pour vous montrer des visites ou des excursions pr\u00e8s de chez vous lorsque vous voyagez. Vous pouvez modifier les param\u00e8tres de confidentialit\u00e9 de votre appareil \u00e0 tout moment afin de d\u00e9sactiver la fonctionnalit\u00e9 permettant de partager des informations de localisation avec l&rsquo;application et \/ ou la fonctionnalit\u00e9 permettant de marquer vos photos avec des informations de localisation. Notez que la d\u00e9sactivation du partage de position peut affecter certaines fonctionnalit\u00e9s de notre application. Si vous avez des questions concernant les param\u00e8tres de confidentialit\u00e9 de votre appareil, nous vous sugg\u00e9rons de contacter le fabricant de votre appareil ou votre fournisseur de services mobiles pour obtenir de l&rsquo;aide.Vos contributionsVous pouvez contribuer aux sites Web du Club Safari de diff\u00e9rentes mani\u00e8res, y compris participer \u00e0 des sondages Nous pouvons stocker ces contributions (votre \u00abContenu\u00bb), les afficher publiquement sur nos sites Web et Applications et ceux de nos partenaires et distributeurs affili\u00e9s, les afficher aux autres utilisateurs, les partager avec nos partenaires et distributeurs affili\u00e9s et les utiliser \u00e0 des fins promotionnelles. Notez que si vous incluez des informations personnelles dans votre contenu, elles peuvent \u00eatre utilis\u00e9es et consult\u00e9es par d&rsquo;autres personnes. Nous ne sommes pas responsables des informations que vous choisissez d&rsquo;inclure dans votre Content.Cookies, et de la fa\u00e7on dont nous les utilisons. Les \u00ab\u00a0Cookies\u00a0\u00bb sont des informations stock\u00e9es par votre navigateur Web sur le disque dur de votre ordinateur, \u00e0 des fins d&rsquo;archivage. Les cookies en eux-m\u00eames identifient seulement votre ordinateur; ils ne vous identifient pas personnellement. Cookies de premi\u00e8re partie: Au Safari Club, nous utilisons des cookies pour nous aider \u00e0 reconna\u00eetre votre navigateur en tant que visiteur pr\u00e9c\u00e9dent et enregistrer et m\u00e9moriser toutes les pr\u00e9f\u00e9rences qui ont pu \u00eatre d\u00e9finies pendant que votre navigateur visitait notre site. informations sur la session, collecter des informations sur la fa\u00e7on dont vous visitez et acc\u00e9der \u00e0 nos sites Web et applications. Nous pouvons \u00e9galement enregistrer votre mot de passe dans un cookie si vous avez coch\u00e9 la case \u00ab\u00a0Enregistrer ce mot de passe pour la connexion automatique\u00a0\u00bb. Veuillez noter que les ID de membre, les mots de passe et toutes les autres donn\u00e9es relatives au compte incluses dans ces cookies sont crypt\u00e9s \u00e0 des fins de s\u00e9curit\u00e9. Nous utilisons \u00e9galement des cookies pour nous aider \u00e0 personnaliser le contenu, l&rsquo;exp\u00e9rience et les publicit\u00e9s qui vous sont fournis sur nos sites Web et Applications et pour analyser et mesurer l&rsquo;efficacit\u00e9 de nos communications par e-mail, fonctionnalit\u00e9s et offres, et publicit\u00e9s. hors des cookies; Cependant, la d\u00e9sactivation des cookies limitera votre utilisation de nos sites Web et applications. Pour en savoir plus sur la modification des param\u00e8tres de cookies de votre navigateur, veuillez consulter le lien d&rsquo;information appropri\u00e9: Internet Explorer: http:\/\/windows.microsoft.com\/fr-FR\/windows-vista\/Cookies-frequently-asked-questionsFirefox: http: \/\/ support.mozilla.org\/fr-FR\/kb\/cookies-information-websites-store-on-your-computerChrome: https:\/\/support.google.com\/chrome\/bin\/answer.py?hl=fr&amp;answer=95647&amp;p= cpn_cookiesSafari: http:\/\/support.apple.com\/kb\/PH5042Third-Party Cookies: Safari Club et ses sites affili\u00e9s s&rsquo;engagent \u00e0 vous fournir du contenu et des informations pertinents sur nos sites. Pour ce faire, nous pouvons collecter des informations\u00e0 propos de vos recherches et autres activit\u00e9s sur le site et \u00e0 utiliser des soci\u00e9t\u00e9s de publicit\u00e9 tierces pour diffuser des annonces pendant que vous visitez nos sites Web et nous permettons \u00e0 ces soci\u00e9t\u00e9s de placer et d&rsquo;acc\u00e9der \u00e0 leurs propres cookies sur votre ordinateur. Ces annonceurs n&rsquo;ont pas acc\u00e8s aux informations que nous recueillons via les cookies de Safari Club. L&rsquo;utilisation des cookies par d&rsquo;autres entreprises est soumise \u00e0 leurs propres politiques de confidentialit\u00e9 et non aux n\u00f4tres. Balises Web: Nos sites Web peuvent \u00e9galement utiliser des pixels invisibles (\u00e9galement appel\u00e9s pixels invisibles, pixels invisibles ou bogues Web), qui sont de minuscules graphiques avec un identifiant unique , similaire en fonction aux cookies, qui sont plac\u00e9s dans le code d&rsquo;une page Web. Nous utilisons des balises Web pour surveiller les mod\u00e8les de trafic des utilisateurs d&rsquo;une page \u00e0 l&rsquo;autre, pour livrer ou communiquer avec des cookies, pour savoir si vous \u00eates venu sur notre site \u00e0 partir d&rsquo;une publicit\u00e9 en ligne affich\u00e9e sur un site tiers et am\u00e9liorer les performances du site. Nous pouvons \u00e9galement permettre \u00e0 nos fournisseurs de services d&rsquo;utiliser des balises Web pour nous aider \u00e0 comprendre quels courriels ont \u00e9t\u00e9 ouverts par les destinataires et pour suivre le trafic des visiteurs et les actions sur notre site. Cela nous permet de mesurer l&rsquo;efficacit\u00e9 de notre contenu et d&rsquo;autres offres.Donn\u00e9es collect\u00e9es par les partenaires commerciaux et les r\u00e9seaux publicitaires pour vous proposer des publicit\u00e9s pertinentes: Bon nombre des publicit\u00e9s que vous voyez sur la gamme Safari Club sont servies par Safari Club ou ses prestataires ; Toutefois, nous autorisons \u00e9galement les tiers \u00e0 collecter des informations sur vos activit\u00e9s en ligne \u00e0 l&rsquo;aide de cookies et d&rsquo;autres technologies. Ces tiers comprennent (1) les partenaires commerciaux, qui recueillent des informations lorsque vous consultez ou interagissez avec l&rsquo;une de leurs publicit\u00e9s sur nos sites, et (2) les r\u00e9seaux publicitaires qui collectent des informations sur vos int\u00e9r\u00eats lorsque vous consultez ou interagissez avec l&rsquo;une des publicit\u00e9s ils placent sur de nombreux sites Web diff\u00e9rents sur Internet. Les informations recueillies par ces tiers sont utilis\u00e9es pour faire des pr\u00e9dictions sur vos caract\u00e9ristiques, vos int\u00e9r\u00eats ou vos pr\u00e9f\u00e9rences et pour afficher des publicit\u00e9s sur nos sites et sur Internet adapt\u00e9es \u00e0 vos int\u00e9r\u00eats apparents.Veuillez noter que nous n&rsquo;avons pas acc\u00e8s aux cookies ou d&rsquo;autres technologies que ces tiers peuvent utiliser pour collecter des informations sur vos int\u00e9r\u00eats, et les pratiques d&rsquo;information de ces tiers ne sont pas couvertes par la pr\u00e9sente Politique de confidentialit\u00e9. Certaines de ces soci\u00e9t\u00e9s sont membres de Network Advertising Initiative, qui offre un emplacement unique pour refuser le ciblage publicitaire des entreprises membres. R\u00e9ponse aux signaux de non-suivi: Votre navigateur Web peut transmettre un message \u00abNe pas suivre\u00bb (\u00abDNT\u00bb) signaler au Safari Club et \u00e0 d&rsquo;autres sites Web. En raison des diff\u00e9rences dans les param\u00e8tres par d\u00e9faut des navigateurs Web et de la mani\u00e8re dont les navigateurs int\u00e8grent les signaux DNT, il est parfois difficile de d\u00e9terminer si les visiteurs du site ont s\u00e9lectionn\u00e9 eux-m\u00eames les param\u00e8tres DNT ou s&rsquo;ils savent qu&rsquo;ils ont le choix. . Le Safari Club ne r\u00e9pond pas actuellement aux signaux DNT. Une fois que l&rsquo;industrie de l&rsquo;Internet aura \u00e9tabli les normes relatives \u00e0 ce probl\u00e8me et que Safari Club reconna\u00eetra ces normes, nous pourrons r\u00e9\u00e9valuer cette approche.Comment utilisons-nous et divulguons-nous vos renseignements personnelsNous utilisons vos renseignements personnels de la fa\u00e7on suivante: Pour vous inscrire et g\u00e9rer votre compte, y compris pour permettre votre acc\u00e8s et utilisation de notre site; pour communiquer avec vous en g\u00e9n\u00e9ral, y compris pour fournir des informations sur Safari Club et des invitations de la famille de soci\u00e9t\u00e9s Safari ClubPour vous fournir les informations que vous demandez sur nos produitsPour vous envoyer des e-mails marketing et des informationsPour permettre \u00e0 nos fournisseurs tiers de r\u00e9pondre \u00e0 vos r\u00e9servations confirmer vos achatsPour vous assurer que vous \u00eates correctement factur\u00e9Pour nous permettre de publier le contenu que vous nous soumettez \u00e0 notre famille de sites Web et sur nos applicationsPour mesurer et suivre les d\u00e9tails d\u00e9mographiques de nos clientsPour cibler le contenu sur notre site Web pour mieux correspondre \u00e0 vos int\u00e9r\u00eats avec Safari Club, y compris la personnalisation des annonces qui vous sont pr\u00e9sent\u00e9esPour cibler le contenu appropri\u00e9 pour les messages de marketing par courriel afin de mieux r\u00e9pondre \u00e0 vos int\u00e9r\u00eatsPour r\u00e9pondre \u00e0 vos questions et commentairesPour mesurer l&rsquo;int\u00e9r\u00eat et am\u00e9liorer nos produits, services, sites Web et ApplicationsPour vous informer des offres et produits services disponibles chez nous ou o Vous pouvez solliciter des informations aupr\u00e8s de vous, y compris par le biais de sondagesPour r\u00e9soudre des conflits ou r\u00e9soudre des probl\u00e8mesPour \u00e9viter des activit\u00e9s potentiellement interdites ou ill\u00e9galesAppliquer nos Conditions d&rsquo;utilisationNous vous d\u00e9crivons au point de ventePour adapter nos produits et services \u00e0 vos besoins les int\u00e9r\u00eats personnels et la mani\u00e8re dont les visiteurs utilisent nos sites, applications et m\u00e9dias sociaux pour exploiter, \u00e9valuer et am\u00e9liorer notre entreprise et les produits et services que nous offronspour analyser et am\u00e9liorer nos communications et strat\u00e9gies marketing (y compris enAnalyser les tendances et les statistiques concernant l&rsquo;utilisation par les visiteurs de nos sites, applications mobiles et m\u00e9dias sociaux, et les achats effectu\u00e9s par les visiteurs sur nos sitesPour prot\u00e9ger et pr\u00e9venir la fraude, les transactions non autoris\u00e9es, les r\u00e9clamations et autres Nous vous proposerons des choix concernant l&rsquo;utilisation et la divulgation de vos informations personnelles \u00e0 des fins de marketing.Partage avec les services de m\u00e9dias sociauxSi vous vous connectez \u00e0 Safari Club en utilisant Facebook, nous pouvons montrer vos avis, photos et visites que vos amis Facebook ont \u200b\u200bpubli\u00e9s, partag\u00e9s, sauvegard\u00e9s ou achet\u00e9s sur Safari Club. Notez que si vous avez des amis Facebook qui utilisent Safari Club, ils peuvent \u00e9galement partager des informations \u00e0 votre sujet avec nous via Facebook. Si vous souhaitez emp\u00eacher ce partage, veuillez consulter vos param\u00e8tres de confidentialit\u00e9 Facebook. Vous pouvez \u00e9galement choisir d&rsquo;acc\u00e9der aux sites Web et services de m\u00e9dias sociaux tiers via Safari Club (tels que Facebook et Twitter). Lorsque vous le faites, vous partagez des informations avec ces sites, et les informations que vous partagez sont r\u00e9gies par leurs politiques de confidentialit\u00e9. Vous pouvez \u00e9galement modifier vos param\u00e8tres de confidentialit\u00e9 avec ces sites Web de m\u00e9dias sociaux tiers.Partage avec les fournisseurs de servicesCertains des renseignements personnels que nous recueillons sont partag\u00e9s avec nos fournisseurs de services (p. Ex. Tour-op\u00e9rateurs) qui participent directement aux achats que vous avez effectu\u00e9s. de notre part. Nous ne fournissons \u00e0 nos fournisseurs de services que votre nom et vos coordonn\u00e9es locales, si vous les fournissez (par exemple, le nom de votre h\u00f4tel pour les enl\u00e8vements et les restitutions, votre num\u00e9ro de t\u00e9l\u00e9phone local, votre num\u00e9ro de t\u00e9l\u00e9phone portable, votre adresse e-mail, etc. Nous ne fournissons \u00e0 nos fournisseurs de services aucune autre information personnelle. Si vous d\u00e9cidez de fournir des renseignements personnels directement \u00e0 un fournisseur de services, nous vous recommandons de consulter la politique de confidentialit\u00e9 du fournisseur de services pour d\u00e9terminer comment ce fournisseur de services peut utiliser ou divulguer vos renseignements personnels.Partage avec des fournisseurs tiersNous partageons \u00e9galement vos renseignements personnels avec des tiers les fournisseurs de services partiels qui fournissent des services ou des fonctions en notre nom, y compris l&rsquo;analytique commerciale, le traitement des paiements, le service \u00e0 la client\u00e8le, le marketing, les relations publiques, la distribution de sondages ou de loteries et la pr\u00e9vention de la fraude. Nous pouvons \u00e9galement autoriser des fournisseurs tiers \u00e0 collecter des informations en notre nom, y compris, par exemple, si n\u00e9cessaire pour exploiter les fonctionnalit\u00e9s de nos sites Web ou Applications ou pour faciliter la diffusion de publicit\u00e9s en ligne adapt\u00e9es \u00e0 vos int\u00e9r\u00eats. Les fournisseurs tiers ont acc\u00e8s \u00e0 et peuvent collecter des informations uniquement au besoin pour ex\u00e9cuter leurs fonctions et ne sont pas autoris\u00e9s \u00e0 partager ou \u00e0 utiliser les informations \u00e0 d&rsquo;autres fins. Nous concluons actuellement des contrats avec plusieurs partenaires tiers pour g\u00e9rer et optimiser notre Internet. affaires et communications. Nous utilisons les services de soci\u00e9t\u00e9s de marketing tierces pour nous aider \u00e0 mesurer l&rsquo;efficacit\u00e9 de notre publicit\u00e9 et la fa\u00e7on dont les visiteurs utilisent notre site Web. Pour ce faire, nous utilisons des balises Web et des cookies fournis par ces soci\u00e9t\u00e9s de marketing en relation avec nos sites Web. Les informations que nous collectons nous aident \u00e0 apprendre quelles sont les pages les plus attractives pour nos visiteurs, quels produits int\u00e9ressent le plus nos clients et quels types d&rsquo;offres nos clients aiment voir. Partage avec les sites r\u00e9f\u00e9rents Si vous avez \u00e9t\u00e9 r\u00e9f\u00e9r\u00e9 \u00e0 Safari Club par un autre site Web, nous pouvons partager vos informations d&rsquo;inscription, telles que votre nom, adresse e-mail, adresse postale, num\u00e9ro de t\u00e9l\u00e9phone et pr\u00e9f\u00e9rences de voyage, \u00e0 votre sujet avec ce site r\u00e9f\u00e9rant. Nous n&rsquo;avons pas impos\u00e9 de restrictions sur l&rsquo;utilisation des informations personnelles par les sites r\u00e9f\u00e9rents et nous vous encourageons \u00e0 consulter les politiques de confidentialit\u00e9 de tout site Web qui vous a r\u00e9f\u00e9r\u00e9 \u00e0 Safari Club.Partage avec des soci\u00e9t\u00e9s au sein de notre famille d&rsquo;entrepriseNous pouvons partager vos informations personnelles au sein du groupe Safari Club des entreprises ainsi que notre soci\u00e9t\u00e9 m\u00e8re, Tours en Cr\u00e8te, et nos soci\u00e9t\u00e9s affili\u00e9es et sites Web nationaux et internationaux. Ce partage nous permet de vous fournir des informations sur les produits et services, li\u00e9s au voyage et autres, susceptibles de vous int\u00e9resser. Dans la mesure o\u00f9 notre soci\u00e9t\u00e9 m\u00e8re et nos soci\u00e9t\u00e9s affili\u00e9es ont acc\u00e8s \u00e0 vos informations, elles suivront des pratiques au moins aussi restrictives que les pratiques d\u00e9crites dans cette Politique de confidentialit\u00e9. Ils se conformeront \u00e9galement aux lois applicables r\u00e9gissant la transmission des communications promotionnelles et, au minimum, vous donneront l&rsquo;occasion, dans tout courriel commercial qu&rsquo;ils envoient, de choisir de ne plus recevoir de tels messages \u00e0 l&rsquo;avenir.Autre partageNous pouvons \u00e9galement utiliser ou divulguer des renseignements personnels comme nous le jugeons n\u00e9cessaire ou appropri\u00e9: (a) en vertu de la loi applicable, y compris les lois en dehors de votre pays de r\u00e9sidence; (b) de se conformer \u00e0 des assignations \u00e0 compara\u00eetre, \u00e0 des ordonnances judiciaires ou \u00e0 d&rsquo;autres proc\u00e9dures judiciaires l\u00e9gitimes et ex\u00e9cutoires; c) r\u00e9pondre aux demandes du public oules autorit\u00e9s gouvernementales, y compris les autorit\u00e9s publiques ou gouvernementales en dehors de votre pays de r\u00e9sidence; (d) faire respecter nos termes et conditions ou autrement \u00e9tablir ou exercer nos droits l\u00e9gaux; (e) prot\u00e9ger et d\u00e9fendre nos droits, nos biens ou notre s\u00e9curit\u00e9 ou ceux de nos soci\u00e9t\u00e9s affili\u00e9es, de nos clients ou d&rsquo;autres personnes; (f) pour prot\u00e9ger nos droits, notre vie priv\u00e9e, notre s\u00e9curit\u00e9 ou nos biens, ou ceux de nos soci\u00e9t\u00e9s affili\u00e9es, vous ou d&rsquo;autres; g) nous permettre de poursuivre les recours disponibles ou de limiter les dommages que nous pourrions subir; h) enqu\u00eater, emp\u00eacher ou prendre des mesures concernant des activit\u00e9s ill\u00e9gales ou pr\u00e9sum\u00e9es ill\u00e9gales; (i) dans le cadre d&rsquo;une transaction corporative, telle qu&rsquo;une cession, une fusion, une consolidation ou une vente d&rsquo;actifs, ou dans le cas improbable d&rsquo;une faillite; ou (j) tel que requis par la loi. Nous pouvons utiliser et divulguer d&rsquo;autres informations pour n&rsquo;importe quel but. Dans certains cas, nous pouvons combiner d&rsquo;autres informations avec des informations personnelles (telles que la combinaison de votre nom avec votre emplacement g\u00e9ographique). Si nous combinons toute autre information avec des informations personnelles, les informations combin\u00e9es seront trait\u00e9es par nous comme des informations personnelles, tant qu&rsquo;elles sont combin\u00e9es. Nous pouvons \u00e9galement partager des informations agr\u00e9g\u00e9es ou anonymes avec des tiers, y compris les annonceurs et les investisseurs. Par exemple, nous pouvons indiquer \u00e0 nos annonceurs le nombre de visiteurs que notre site Web re\u00e7oit ou les excursions ou visites les plus populaires. Ces informations ne contiennent aucune information personnelle et sont utilis\u00e9es pour d\u00e9velopper du contenu et des services que nous esp\u00e9rons vous int\u00e9resser. Communications \u00e9lectroniques que vous pouvez attendre de Safari ClubNous pouvons vous envoyer des courriels de marketing avec des informations sur les offres, destinations et produits Safari Club des nouvelles, des offres, des concours et d&rsquo;autres promotions sp\u00e9ciales que nous croyons que vous trouverez utiles, int\u00e9ressantes ou informatives. Nous vous fournirons des choix concernant notre utilisation de vos informations personnelles \u00e0 des fins de marketing. Si vous ne souhaitez plus recevoir de communications par e-mail de la part de Safari Club, vous avez le choix entre plusieurs options: Vous pouvez vous d\u00e9sabonner \u00e0 tout moment en suivant les instructions et le lien inclus dans chaque e-mail marketing envoy\u00e9.Veuillez noter M\u00eame si vous refusez de recevoir de futures communications marketing de Safari Club, nous continuerons \u00e0 vous envoyer des courriels concernant vos achats et vos r\u00e9servations, ainsi que des informations administratives telles que des modifications de nos conditions et politiques. Si vous effectuez une r\u00e9servation ou un achat sur l&rsquo;un de nos sites Web, nous pouvons \u00e9galement vous envoyer des informations sur de nouveaux produits ou demander votre avis sur nos sites Web, etc., afin que nous puissions am\u00e9liorer notre service \u00e0 vous et \u00e0 d&rsquo;autres consommateurs. Distributeurs et fournisseursTours, activit\u00e9s et exp\u00e9riences annonc\u00e9s sur notre site sont mis \u00e0 disposition par nos filiales, distributeurs et fournisseurs tiers. Nos affili\u00e9s, distributeurs et fournisseurs peuvent avoir des politiques de confidentialit\u00e9 qui diff\u00e8rent de la politique de confidentialit\u00e9 de Safari Club. Liens externesSi une partie du site Web de Safari Club vous relie \u00e0 d&rsquo;autres sites, ces sites externes ne fonctionnent pas conform\u00e9ment \u00e0 cette politique de confidentialit\u00e9. Nous ne sommes pas responsables des pratiques de confidentialit\u00e9 des autres sites et nous vous recommandons d&rsquo;examiner les d\u00e9clarations de confidentialit\u00e9 publi\u00e9es sur ces autres sites Web pour comprendre leurs proc\u00e9dures de collecte, d&rsquo;utilisation et de divulgation des informations personnelles.Changements \u00e0 notre politique de confidentialit\u00e9Nous savons que notre activit\u00e9 continuera \u00e9voluer \u00e0 mesure que nous introduisons de nouveaux produits, et, \u00e0 ce titre, de temps en temps cette politique de confidentialit\u00e9 peut \u00eatre revue et r\u00e9vis\u00e9e.Safari Club se r\u00e9serve le droit de modifier cette politique de confidentialit\u00e9 en affichant les changements sur son site Web. Vous pouvez d\u00e9terminer quand cette politique de confidentialit\u00e9 a \u00e9t\u00e9 mise \u00e0 jour pour la derni\u00e8re fois en examinant la l\u00e9gende DERNI\u00c8RE MISE \u00c0 JOUR ci-dessus et les r\u00e9visions prendront effet lors de la publication. Nous aviserons nos membres des changements mat\u00e9riels apport\u00e9s \u00e0 cette politique de confidentialit\u00e9 en envoyant un avis \u00e0 l&rsquo;adresse courriel que vous nous avez fournie ou en pla\u00e7ant un avis sur notre site Web. Nous vous encourageons \u00e0 consulter cette politique de confidentialit\u00e9 de temps en temps pour v\u00e9rifier la version la plus r\u00e9cente. L&rsquo;utilisation de nos sites Web ou applications apr\u00e8s qu&rsquo;un avis de modifications vous a \u00e9t\u00e9 envoy\u00e9 ou publi\u00e9 sur notre site Web constitue un consentement \u00e0 la modification des termes et des pratiques<\/p>\n<p>.Nous contacter<\/p>\n<p>Safari Club SA<\/p>\n<p>Parlama 22<\/p>\n<p>70007 Malia Gr\u00e8ce<\/p>\n<p>+ 30 2897032666<\/p>\n<p>info@safariclub.gr[\/vc_column_text][\/vc_column][\/vc_row]\t\t<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Derni\u00e8re mise \u00e0 jour: 27\/04\/2017 Au Safari Club, nous reconnaissons que gagner et conserver votre confiance est l&rsquo;une des choses les plus importantes que nous faisons en tant qu&rsquo;entreprise. Prot\u00e9ger votre vie priv\u00e9e est une responsabilit\u00e9 que nous prenons tr\u00e8s au s\u00e9rieux. Nous avons pr\u00e9par\u00e9 cette politique de confidentialit\u00e9 pour vous aider \u00e0 comprendre comment&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-52647","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/pages\/52647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/comments?post=52647"}],"version-history":[{"count":1,"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/pages\/52647\/revisions"}],"predecessor-version":[{"id":53918,"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/pages\/52647\/revisions\/53918"}],"wp:attachment":[{"href":"https:\/\/safariclub.gr\/fr\/wp-json\/wp\/v2\/media?parent=52647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}